{"id":32,"count":1,"description":"","link":"https:\/\/adriafly.me\/en\/tag\/tasmanijski\/","name":"Tasmanijski","slug":"tasmanijski","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tasmanijski Arhive - Adriafly - Paragliding Club<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adriafly.me\/en\/tag\/tasmanijski\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tasmanijski Arhive - Adriafly - Paragliding Club\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adriafly.me\/en\/tag\/tasmanijski\/\" \/>\n<meta property=\"og:site_name\" content=\"Adriafly - Paragliding Club\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adriafly.me\/wp-content\/uploads\/2024\/01\/naslovna.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/adriafly.me\\\/tag\\\/tasmanijski\\\/\",\"url\":\"https:\\\/\\\/adriafly.me\\\/tag\\\/tasmanijski\\\/\",\"name\":\"Tasmanijski Arhive - Adriafly - Paragliding Club\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adriafly.me\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adriafly.me\\\/tag\\\/tasmanijski\\\/#breadcrumb\"},\"inLanguage\":\"en-NZ\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adriafly.me\\\/tag\\\/tasmanijski\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Po\u010detna\",\"item\":\"https:\\\/\\\/adriafly.me\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tasmanijski\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adriafly.me\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/adriafly.me\\\/en\\\/\",\"name\":\"Adriafly - Paragliding Club\",\"description\":\"Paraglajding klub Herceg Novi\",\"publisher\":{\"@id\":\"https:\\\/\\\/adriafly.me\\\/en\\\/#organization\"},\"alternateName\":\"Adriafly\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adriafly.me\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-NZ\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/adriafly.me\\\/en\\\/#organization\",\"name\":\"Adriafly - Paragliding Club\",\"url\":\"https:\\\/\\\/adriafly.me\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-NZ\",\"@id\":\"https:\\\/\\\/adriafly.me\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/adriafly.me\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/02-LOGO-nobackgr.png\",\"contentUrl\":\"https:\\\/\\\/adriafly.me\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/02-LOGO-nobackgr.png\",\"width\":1536,\"height\":1349,\"caption\":\"Adriafly - Paragliding Club\"},\"image\":{\"@id\":\"https:\\\/\\\/adriafly.me\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AdriaFly\",\"https:\\\/\\\/www.instagram.com\\\/adriafly.me\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tasmanijski Arhive - Adriafly - Paragliding Club","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adriafly.me\/en\/tag\/tasmanijski\/","og_locale":"en_US","og_type":"article","og_title":"Tasmanijski Arhive - Adriafly - Paragliding Club","og_url":"https:\/\/adriafly.me\/en\/tag\/tasmanijski\/","og_site_name":"Adriafly - Paragliding Club","og_image":[{"width":1920,"height":1080,"url":"https:\/\/adriafly.me\/wp-content\/uploads\/2024\/01\/naslovna.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/adriafly.me\/tag\/tasmanijski\/","url":"https:\/\/adriafly.me\/tag\/tasmanijski\/","name":"Tasmanijski Arhive - Adriafly - Paragliding Club","isPartOf":{"@id":"https:\/\/adriafly.me\/en\/#website"},"breadcrumb":{"@id":"https:\/\/adriafly.me\/tag\/tasmanijski\/#breadcrumb"},"inLanguage":"en-NZ"},{"@type":"BreadcrumbList","@id":"https:\/\/adriafly.me\/tag\/tasmanijski\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Po\u010detna","item":"https:\/\/adriafly.me\/en\/"},{"@type":"ListItem","position":2,"name":"Tasmanijski"}]},{"@type":"WebSite","@id":"https:\/\/adriafly.me\/en\/#website","url":"https:\/\/adriafly.me\/en\/","name":"Adriafly - Paragliding Club","description":"Paraglajding klub Herceg Novi","publisher":{"@id":"https:\/\/adriafly.me\/en\/#organization"},"alternateName":"Adriafly","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adriafly.me\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-NZ"},{"@type":"Organization","@id":"https:\/\/adriafly.me\/en\/#organization","name":"Adriafly - Paragliding Club","url":"https:\/\/adriafly.me\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-NZ","@id":"https:\/\/adriafly.me\/en\/#\/schema\/logo\/image\/","url":"https:\/\/adriafly.me\/wp-content\/uploads\/2025\/08\/02-LOGO-nobackgr.png","contentUrl":"https:\/\/adriafly.me\/wp-content\/uploads\/2025\/08\/02-LOGO-nobackgr.png","width":1536,"height":1349,"caption":"Adriafly - Paragliding Club"},"image":{"@id":"https:\/\/adriafly.me\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AdriaFly","https:\/\/www.instagram.com\/adriafly.me\/"]}]}},"_links":{"self":[{"href":"https:\/\/adriafly.me\/en\/wp-json\/wp\/v2\/tags\/32","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adriafly.me\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/adriafly.me\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/adriafly.me\/en\/wp-json\/wp\/v2\/posts?tags=32"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}